{"id":17561,"date":"2026-05-11T12:33:02","date_gmt":"2026-05-11T16:33:02","guid":{"rendered":"https:\/\/operadequebec.com\/?page_id=17561"},"modified":"2026-07-12T18:34:26","modified_gmt":"2026-07-12T22:34:26","slug":"carmelites-festival-2026","status":"publish","type":"page","link":"https:\/\/operadequebec.com\/en\/carmelites-festival-2026\/","title":{"rendered":"Festival 2026 &#8211; Dialogues des Carm\u00e9lites"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"17561\" class=\"elementor elementor-17561 elementor-17560\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2605536 min-100vh e-con-full e-flex e-con e-parent\" data-id=\"2605536\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53b7251 e-con-full home-prog-infos e-flex e-con e-parent\" data-id=\"53b7251\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a5e177b e-con-full e-flex e-con e-child\" data-id=\"a5e177b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6d6bdb2 e-con-full home-prog-infos-left e-flex e-con e-child\" data-id=\"6d6bdb2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35b07aa wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"35b07aa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DIALOGUES OF THE CARMELITES<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9247b1d wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"9247b1d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">by Francis Poulenc <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbe0596 wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"cbe0596\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">With the Orchestre symphonique de Qu\u00e9bec and the Op\u00e9ra de Qu\u00e9bec Chorus<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c571717 wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"c571717\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Dates:<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68385c4 wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"68385c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">July 28 at 7:30 p.m.\u00a0<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbe713c wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"fbe713c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">July 30 at 7:30 p.m.\u00a0<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b2e77f wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"7b2e77f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">August 1 at 2:00 p.m.<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5dae9d wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"e5dae9d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Location:<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d2ceef wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"2d2ceef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Louis-Fr\u00e9chette Hall, Grand Th\u00e9\u00e2tre de Qu\u00e9bec<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44c82a1 wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"44c82a1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Language: <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-684f2db wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"684f2db\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">In French with French surtitles<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1009d6c wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"1009d6c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Duration:<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-522c024 wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"522c024\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">2h45, including a 25-minute intermission<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bab736 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-shortcode\" data-id=\"5bab736\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class='w3eden'><!-- WPDM Link Template: Button Template -->\n\n<a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/operadequebec.com\/en\/download\/programme-carmen\/?wpdmdl=16764&refresh=6a56fa2a4ceca1784085034\">Programme Carmen<\/a><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f620aa2 e-con-full e-flex e-con e-child\" data-id=\"f620aa2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b1fcecf e-con-full home-prog-infos-right e-flex e-con e-child\" data-id=\"b1fcecf\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1a660f wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"d1a660f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Buy tickets\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84e7521 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"84e7521\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">20 % DE RABAIS EN PR\u00c9VENTE JUSQU\u2019AU 26 MAI<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7832a94 elementor-align-justify elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"7832a94\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/am.ticketmaster.com\/operadequebec\/en\/buy\/ism\/TDcyNjIwMDE=\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">JULY 28, 2025 AT 7:30 P.M.<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aee878 elementor-align-justify elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"4aee878\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/am.ticketmaster.com\/operadequebec\/en\/buy\/ism\/TDcyNjIwMDI=\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">JULY 30, 2025 AT 7:30 P.M.<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af33213 elementor-align-justify elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"af33213\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/am.ticketmaster.com\/operadequebec\/en\/buy\/ism\/TDcyNjIwMDM=\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">AUGUST 1, 2025 AT 2:00 P.M.<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2349e14 elementor-align-justify elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"2349e14\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/am.ticketmaster.com\/operadequebec\/en\/buy?id=MzE3\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SUBSCRIBE!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2e9cc7 wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"b2e9cc7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">By phone:<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f84dc11 wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"f84dc11\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Grand Th\u00e9\u00e2tre de Qu\u00e9bec box office<br \/>\n<span style=\"font-weight:600\"> <a href=\"tel:4186438131\" target=\"_blank\">418 643-8131<\/a> <\/span><br \/>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46e75df wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"46e75df\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">In person:<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d86764e wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"d86764e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-default\">269 Ren\u00e9-L\u00e9vesque Blvd. East,,<br \/>\nQuebec City, Quebec)<br \/>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c3b1850 e-con-full darkback e-flex e-con e-parent\" data-id=\"c3b1850\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c2d4c43 e-con-full e-flex e-con e-child\" data-id=\"c2d4c43\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4978252 e-con-full e-flex e-con e-child\" data-id=\"4978252\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f289fbe e-con-full e-flex e-con e-child\" data-id=\"f289fbe\" data-element_type=\"container\">\n\t\t\t\t<div data-split-settings=\"{&quot;type&quot;:&quot;chars&quot;,&quot;animation&quot;:&quot;fadeInUp2&quot;}\" class=\"elementor-element elementor-element-74be1ba wavo-headig-split heading-has-split-yes wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"74be1ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A co-production of the Th\u00e9\u00e2tre des Champs-\u00c9lys\u00e9es, Paris, La Monnaie \/ De Munt, Brussels, and the Festival d\u2019op\u00e9ra de Qu\u00e9bec<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe9d38d e-con-full e-flex e-con e-child\" data-id=\"fe9d38d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-366acb3 wavo-headig-line heading-has-line-yes elementor-widget__width-initial wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"366acb3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Opera in Three Acts<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-93c3bbc e-con-full e-flex e-con e-child\" data-id=\"93c3bbc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-befc67c elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"befc67c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Music: Francis Poulenc<\/p><p>Text by Georges Bernanos<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5e074b e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"d5e074b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation_tablet&quot;:&quot;none&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21bc848 elementor-invisible elementor-widget elementor-widget-wavo-popup-video\" data-id=\"21bc848\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:1500,&quot;_animation_tablet&quot;:&quot;fadeInDown&quot;,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"wavo-popup-video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"popup-video-wrapper video-21bc848\"><a class=\"popup-video\" href=\"https:\/\/www.youtube.com\/watch?v=QmqGpO62Ag0\"><div class=\"vid-btn\"><span class=\"icon\"><i class=\"fas fa-play\"><\/i><\/span><\/div><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fde703 e-con-full e-flex e-con e-child\" data-id=\"1fde703\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-55b58a0 e-flex e-con-boxed e-con e-child\" data-id=\"55b58a0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be605f9 elementor-widget elementor-widget-text-editor\" data-id=\"be605f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Inspired by a true story from the French Revolution, Francis Poulenc\u2019s <em>Dialogues des Carm\u00e9lites<\/em> stands as one of the great pinnacles of French opera, regularly described by major houses and critics as a profound, existential work on fear, death, and faith.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2dd9be elementor-widget elementor-widget-text-editor\" data-id=\"f2dd9be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Through the story of Blanche de La Force, a young woman confronted with fear, doubt, and the burden of choice, the opera tackles with rare intensity questions that still speak to us today: inner freedom, individual conscience, faith, courage, and the struggle to remain standing in the face of political oppression.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0cc780 elementor-widget elementor-widget-text-editor\" data-id=\"e0cc780\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>In this searing production by Olivier Py (seen on major stages around the world and widely hailed for its stark visual power), <em>Dialogues des Carm\u00e9lites<\/em> comes to life with a cast of Qu\u00e9bec artists currently shining on the international scene. A deeply human work, whose spiritual, political and intimate dimensions resonate with particular poignancy in today\u2019s world.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c6bfc3 elementor-widget elementor-widget-text-editor\" data-id=\"0c6bfc3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>A co-production of the Th\u00e9\u00e2tre des Champs-\u00c9lys\u00e9es, Paris, La Monnaie \/ De Munt, Brussels, and the Festival d\u2019op\u00e9ra de Qu\u00e9bec<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ce0e91 elementor-widget elementor-widget-text-editor\" data-id=\"3ce0e91\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>_<\/strong><\/p><p><strong>From History to Opera: Discovering Francis Poulenc\u2019s Dialogues des Carm\u00e9lites<\/strong><br \/><strong>Discussion moderated by Catherine Ferland, PhD, Historian<\/strong><br \/>Sunday, July 5 at 1:30 p.m.<br \/>Duration: 60 minutes<\/p><p><strong>Monast\u00e8re des Augustines<\/strong><br \/>77 rue des Remparts, Qu\u00e9bec City<br \/>&#8220;Communaut\u00e9&#8221; Room<\/p><p>\u00a0<\/p><p><strong>Sliding scale pricing:<\/strong> $12, $16, or $20 (includes admission to the Museum on the day of your visit)<\/p><p><a href=\"https:\/\/www.eventbrite.ca\/e\/billets-de-lhistoire-a-lopera-a-la-decouverte-du-dialogues-des-carmelites-1991708341264?aff=oddtdtcreator&amp;fbclid=IwY2xjawSX6ntleHRuA2FlbQIxMABicmlkETFyaFd6bmxjcWFBYzZlc0pSc3J0YwZhcHBfaWQQMjIyMDM5MTc4ODIwMDg5MgABHuS8ougqiujVbl0Fdo6FaYiAxGAGSCbg2Mgjc0ZLVEfqpyKVJhbM6XMd9uU8_aem_0vk5_gepYtQUSqJ6OHthQA\">RESERVATION<\/a><\/p><p>\u00a0<\/p><p>Guest Speakers:<br \/>&#8211; <strong>Anthony J. Steinhoff<\/strong>, Professor of European and Religious History at the Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al<\/p><p>&#8211;<strong> Ir\u00e8ne Brisson<\/strong>, Musicologist and Retired Professor from the Conservatoire de musique de Qu\u00e9bec<\/p><p>\u00a0<\/p><p>How did a tragedy from the French Revolution become one of the greatest operas of the 20th century?<\/p><p>\u00a0<\/p><p>Join us for an exceptional discussion moderated by historian Catherine Ferland, and discover the fascinating history of the Martyrs of Compi\u00e8gne along with a behind-the-scenes look at Francis Poulenc&#8217;s opera, Dialogues des Carm\u00e9lites.<\/p><p>\u00a0<\/p><p>The Festival d&#8217;op\u00e9ra de Qu\u00e9bec would like to thank the Monast\u00e8re des Augustines.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wavo-column-gap-default elementor-section elementor-top-section elementor-element elementor-element-f5b9e87 nt-section section-padding elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5b9e87\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-602e352\" data-id=\"602e352\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"wavo-column-gap-default elementor-section elementor-inner-section elementor-element elementor-element-6adc97f grille-artistes elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6adc97f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0798ac1\" data-id=\"0798ac1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-split-settings=\"{&quot;type&quot;:&quot;chars&quot;,&quot;animation&quot;:&quot;fadeInUp2&quot;}\" class=\"elementor-element elementor-element-169682f wavo-headig-split heading-has-split-yes wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"169682f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Project Masters<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ffc1a9d\" data-id=\"ffc1a9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6625451 elementor-widget elementor-widget-wavo-team-member\" data-id=\"6625451\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/Opera-de-quebec-jean-marie-zeitouni.jpg\" alt=\"Opera-de-quebec-jean-marie-zeitouni.jpg\"><div class=\"info\"><h6 class=\"team-name\">Musical direction<\/h6><p>Jean-Marie Zeitouni<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/jmzeitouni.com\/fr\/\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-417a97b\" data-id=\"417a97b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-443e3ac elementor-widget elementor-widget-wavo-team-member\" data-id=\"443e3ac\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/04\/festival-opera-de-quebec-olivier-py.jpg\" alt=\"festival-opera-de-quebec-olivier-py.jpg\"><div class=\"info\"><h6 class=\"team-name\">Direction<\/h6><p>Olivier Py<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/www.chatelet.com\/artiste\/py-olivier\/\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f81815f\" data-id=\"f81815f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea863f2 elementor-widget elementor-widget-text-editor\" data-id=\"ea863f2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Musical direction:<\/p><p>Jean-Marie Zeitouni<\/p><p>Direction:<\/p><p>Olivier Py<\/p><p>Revival direction:<\/p><p>Daniel Izzo<\/p><p>Set and costumes design:<\/p><p>Pierre-Andr\u00e9 Weitz<\/p><p>Lighting design:<\/p><p>Bertrand Killy<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"wavo-column-gap-default elementor-section elementor-top-section elementor-element elementor-element-4baf128 nt-section section-padding elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4baf128\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c35d51\" data-id=\"3c35d51\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"wavo-column-gap-default elementor-section elementor-inner-section elementor-element elementor-element-33e8d57 grille-artistes elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33e8d57\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7367f7b\" data-id=\"7367f7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-split-settings=\"{&quot;type&quot;:&quot;chars&quot;,&quot;animation&quot;:&quot;fadeInUp2&quot;}\" class=\"elementor-element elementor-element-ff79dc8 wavo-headig-split heading-has-split-yes wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"ff79dc8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cast<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c6f805a\" data-id=\"c6f805a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06a954a elementor-widget elementor-widget-wavo-team-member\" data-id=\"06a954a\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/06\/foq26-opera-de-quebec-helene-guilmette-credit-luc-robitaille.jpg\" alt=\"foq26-opera-de-quebec-helene-guilmette-credit-luc-robitaille.jpg\"><div class=\"info\"><h6 class=\"team-name\">BLANCHE DE LA FORCE<\/h6><p>H\u00e9l\u00e8ne Guilmette<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/www.heleneguilmette.com\/\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ae0e38e\" data-id=\"ae0e38e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef7fbc9 elementor-widget elementor-widget-wavo-team-member\" data-id=\"ef7fbc9\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/opera-de-quebec-andreanne-gauthier.jpg\" alt=\"opera-de-quebec-andreanne-gauthier.jpg\"><div class=\"info\"><h6 class=\"team-name\">MOTHER MARIE DE L'INCARNATION<\/h6><p>Julie Boulianne<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/www.julieboulianne.ca\/accueil\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-94317e9\" data-id=\"94317e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dac506f elementor-widget elementor-widget-wavo-team-member\" data-id=\"dac506f\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/festival-opera-de-quebec-sylvie-brunet.jpg\" alt=\"festival-opera-de-quebec-sylvie-brunet.jpg\"><div class=\"info\"><h6 class=\"team-name\">MADAME DE CROISSY<\/h6><p>Sylvie Brunet-Grupposo<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/www.hilbert.de\/en\/artists\/singers\/mezzo-soprano\/sylvie-brunet\/\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wavo-column-gap-default elementor-section elementor-inner-section elementor-element elementor-element-5679024 grille-artistes elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5679024\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-71e5d5e\" data-id=\"71e5d5e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a6c9f1 elementor-widget elementor-widget-wavo-team-member\" data-id=\"3a6c9f1\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/04\/festival-opera-de-quebec-guylaine-girard.jpg\" alt=\"festival-opera-de-quebec-guylaine-girard.jpg\"><div class=\"info\"><h6 class=\"team-name\">MADAME LIDOINE<\/h6><p>Guylaine Girard<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/guylaine-girard.com\/\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-84b8adc\" data-id=\"84b8adc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5446113 elementor-widget elementor-widget-wavo-team-member\" data-id=\"5446113\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/Opera-de-quebec-florie-valiquette.jpg\" alt=\"Opera-de-quebec-florie-valiquette.jpg\"><div class=\"info\"><h6 class=\"team-name\">SISTER CONSTANCE DE SAINT DENIS<\/h6><p>Florie Valiquette<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/www.florievaliquette.com\/nouvelle-page\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-fb203cb\" data-id=\"fb203cb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5180447 elementor-widget elementor-widget-wavo-team-member\" data-id=\"5180447\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/opera-de-quebec-patrick-bolleire.jpg\" alt=\"opera-de-quebec-patrick-bolleire.jpg\"><div class=\"info\"><h6 class=\"team-name\">THE MARQUIS DE LA FORCE<\/h6><p>Patrick Bolleire<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/www.patrickbolleire.com\/\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b3ad474\" data-id=\"b3ad474\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-042b1b4 elementor-widget elementor-widget-wavo-team-member\" data-id=\"042b1b4\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2024\/06\/Festival-opera-de-quebec-frederic-antoun.jpg\" alt=\"Festival-opera-de-quebec-frederic-antoun.jpg\"><div class=\"info\"><h6 class=\"team-name\">THE CHEVALIER DE LA FORCE<\/h6><p>Fr\u00e9d\u00e9ric Antoun<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/www.deanartists.com\/frederic-antoun\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wavo-column-gap-default elementor-section elementor-inner-section elementor-element elementor-element-3969544 grille-artistes elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3969544\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-df4e1cd\" data-id=\"df4e1cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c43ce91 elementor-widget elementor-widget-wavo-team-member\" data-id=\"c43ce91\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/06\/opera-de-quebec-rachel-tremblay.jpg\" alt=\"opera-de-quebec-rachel-tremblay.jpg\"><div class=\"info\"><h6 class=\"team-name\">MOTHER JEANNE DE L'ENFANT J\u00c9SUS<\/h6><p>Rach\u00e8le Tremblay<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/lacharpie.wixsite.com\/racheletremblaymezzo\/a-propos\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4d06d5d\" data-id=\"4d06d5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe8f36f elementor-widget elementor-widget-wavo-team-member\" data-id=\"fe8f36f\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/03\/Opera-de-Quebec-Festval-Romeo-et-Juliette-Marie-Andree-Mathieu-2.jpg\" alt=\"Opera-de-Quebec-Festval-Romeo-et-Juliette-Marie-Andree-Mathieu-2.jpg\"><div class=\"info\"><h6 class=\"team-name\">SISTER MATHLIDE<\/h6><p>Marie-Andr\u00e9e Mathieu<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/marieandreemathieu.com\/\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f627466\" data-id=\"f627466\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ceaa7b0 elementor-widget elementor-widget-wavo-team-member\" data-id=\"ceaa7b0\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2024\/04\/opera-de-quebec-hugo-laporte-il-torovatore.jpg\" alt=\"opera-de-quebec-hugo-laporte-il-torovatore.jpg\"><div class=\"info\"><h6 class=\"team-name\">THE JAILER \/ MONSIEUR JAVELINOT \/ THIERRY<\/h6><p>Hugo Laporte<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/www.hugolaporte.ca\/\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus-circle\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c6811d4\" data-id=\"c6811d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b7193c elementor-widget elementor-widget-wavo-team-member\" data-id=\"3b7193c\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/opera-de-quebec-francois-piolino.jpg\" alt=\"opera-de-quebec-francois-piolino.jpg\"><div class=\"info\"><h6 class=\"team-name\">THE CARMELITE CHAPLAIN<\/h6><p>Fran\u00e7ois Piolino<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/www.piolino.fr\/\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wavo-column-gap-default elementor-section elementor-inner-section elementor-element elementor-element-b3b8c1d grille-artistes elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3b8c1d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d7ca70d\" data-id=\"d7ca70d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f745a3f elementor-widget elementor-widget-wavo-team-member\" data-id=\"f745a3f\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2025\/03\/HASLER-Emmanuel-photo-credit-Sebastien-Besson-0pera-de-quebec.jpg\" alt=\"HASLER-Emmanuel-photo-credit-Sebastien-Besson-0pera-de-quebec.jpg\"><div class=\"info\"><h6 class=\"team-name\">THE FIRST COMMISSIONER<\/h6><p>Emmanuel Hasler<\/p><div class=\"social\"><a class=\"social-link\" href=\"\" target=\"_blank\"><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c3749b3\" data-id=\"c3749b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4cf7bc elementor-widget elementor-widget-wavo-team-member\" data-id=\"a4cf7bc\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/06\/opera-de-quebec-marc-andre-caron-nov-2025.jpg\" alt=\"opera-de-quebec-marc-andre-caron-nov-2025.jpg\"><div class=\"info\"><h6 class=\"team-name\">THE SECOND COMMISSIONER<\/h6><p>Marc-Andr\u00e9 Caron<\/p><div class=\"social\"><a class=\"social-link\" href=\"\" target=\"_blank\"><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4cf792d\" data-id=\"4cf792d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcac388 elementor-widget elementor-widget-wavo-team-member\" data-id=\"bcac388\" data-element_type=\"widget\" data-widget_type=\"wavo-team-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"team\"><div class=\"item\"><div class=\"img\"><img decoding=\"async\" class=\"thumparallax\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/03\/Opera-de-Quebec-festival-fille-sans-regiment-Maxence-Lasserre-Engberts_credits-Louise-Leblanc.jpg\" alt=\"Opera-de-Quebec-festival-fille-sans-regiment-Maxence-Lasserre-Engberts_credits-Louise-Leblanc.jpg\"><div class=\"info\"><h6 class=\"team-name\">OFFICER<\/h6><p>Maxence Lasserre-Engberts<\/p><div class=\"social\"><a class=\"social-link\" href=\"https:\/\/www.facebook.com\/maxence.lasserre.e\/\" target=\"_blank\"><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/a><\/div><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a675509\" data-id=\"a675509\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f9e50e e-flex e-con-boxed e-con e-parent\" data-id=\"5f9e50e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div data-split-settings=\"{&quot;type&quot;:&quot;chars&quot;,&quot;animation&quot;:&quot;fadeInUp2&quot;}\" class=\"elementor-element elementor-element-880f04e wavo-headig-split heading-has-split-yes wavo-transform transform-type-translate elementor-widget elementor-widget-heading\" data-id=\"880f04e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our partners<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a38c846 e-flex e-con-boxed e-con e-parent\" data-id=\"a38c846\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-60a110c e-con-full e-flex e-con e-child\" data-id=\"60a110c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e71b328 elementor-widget elementor-widget-image\" data-id=\"e71b328\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.bmo.com\/en-ca\/main\/personal\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"755\" height=\"300\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/03\/bmo-logo-blanc.png\" class=\"attachment-full size-full wp-image-5694\" alt=\"\" srcset=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/03\/bmo-logo-blanc.png 755w, https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/03\/bmo-logo-blanc-300x119.png 300w, https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/03\/bmo-logo-blanc-500x199.png 500w\" sizes=\"(max-width: 755px) 100vw, 755px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6829a31 e-con-full e-flex e-con e-child\" data-id=\"6829a31\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3ce20b elementor-widget elementor-widget-image\" data-id=\"c3ce20b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.quebecor.com\/en\/home\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"223\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/03\/quebecor_tout_blanc_FR.png\" class=\"attachment-full size-full wp-image-5627\" alt=\"\" srcset=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/03\/quebecor_tout_blanc_FR.png 600w, https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/03\/quebecor_tout_blanc_FR-300x112.png 300w, https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/03\/quebecor_tout_blanc_FR-500x186.png 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e441898 e-con-full e-flex e-con e-child\" data-id=\"e441898\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30cafda elementor-widget elementor-widget-image\" data-id=\"30cafda\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/azrielifoundation.org\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2181\" height=\"805\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/06\/Azrieli-Logo-ENG-FR-FINAL.png\" class=\"attachment-full size-full wp-image-9317\" alt=\"\" srcset=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/06\/Azrieli-Logo-ENG-FR-FINAL.png 2181w, https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/06\/Azrieli-Logo-ENG-FR-FINAL-300x111.png 300w, https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/06\/Azrieli-Logo-ENG-FR-FINAL-1024x378.png 1024w, https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/06\/Azrieli-Logo-ENG-FR-FINAL-768x283.png 768w, https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/06\/Azrieli-Logo-ENG-FR-FINAL-1536x567.png 1536w, https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/06\/Azrieli-Logo-ENG-FR-FINAL-2048x756.png 2048w, https:\/\/operadequebec.com\/wp-content\/uploads\/2023\/06\/Azrieli-Logo-ENG-FR-FINAL-500x185.png 500w\" sizes=\"(max-width: 2181px) 100vw, 2181px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59ec5c8f e-flex e-con-boxed e-con e-parent\" data-id=\"59ec5c8f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-63a1a1bd e-con-full e-flex e-con e-child\" data-id=\"63a1a1bd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b93452b elementor-widget elementor-widget-image\" data-id=\"3b93452b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.calq.gouv.qc.ca\/en\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"238\" height=\"99\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/calq-logo-blanc-v2.png\" class=\"attachment-full size-full wp-image-18385\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39995d88 e-con-full e-flex e-con e-child\" data-id=\"39995d88\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33ddb828 elementor-widget elementor-widget-image\" data-id=\"33ddb828\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ville.quebec.qc.ca\/en\/index.aspx\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"130\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/ville-qc-logo-blanc-v4.png\" class=\"attachment-medium size-medium wp-image-18398\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6cd85f0 e-con-full e-flex e-con e-child\" data-id=\"6cd85f0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33166758 elementor-widget elementor-widget-image\" data-id=\"33166758\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.canada.ca\/en.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"48\" src=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/gouvernement-canada-logo-blanc-v3.png\" class=\"attachment-medium size-medium wp-image-18392\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DIALOGUES OF THE CARMELITES by Francis Poulenc With the Orchestre symphonique de Qu\u00e9bec and the Op\u00e9ra de Qu\u00e9bec Chorus Dates: July 28 at 7:30 p.m.\u00a0 July 30 at 7:30 p.m.\u00a0 August 1 at 2:00 p.m. Location: Louis-Fr\u00e9chette Hall, Grand Th\u00e9\u00e2tre de Qu\u00e9bec Language: In French with French surtitles Duration: 2h45, including a 25-minute intermission Buy&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"wavo-elementor-page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":{"0":"post-17561","1":"page","2":"type-page","3":"status-publish","4":"hentry","5":"nt-post-class","6":"","7":"thumb-none","9":"excerpt-none"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Festival 2026 - Dialogues des Carm\u00e9lites - Op\u00e9ra de Qu\u00e9bec<\/title>\n<meta name=\"description\" content=\"Dialogues of the Carmelites, at the 2026 Qu\u00e9bec Opera Festival, presented at the Salle Louis-Fr\u00e9chette at the Grand Th\u00e9\u00e2tre de Qu\u00e9bec.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/operadequebec.com\/carmelites-festival-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival 2026 - Dialogues des Carm\u00e9lites - Op\u00e9ra de Qu\u00e9bec\" \/>\n<meta property=\"og:description\" content=\"Dialogues of the Carmelites, at the 2026 Qu\u00e9bec Opera Festival, presented at the Salle Louis-Fr\u00e9chette at the Grand Th\u00e9\u00e2tre de Qu\u00e9bec.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/operadequebec.com\/carmelites-festival-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Op\u00e9ra de Qu\u00e9bec\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-12T22:34:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/FDOQ-DDC-WEB-avec-titre-1000X1050-8Mai-2026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1051\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/operadequebec.com\/carmelites-festival-2026\/\",\"url\":\"https:\/\/operadequebec.com\/carmelites-festival-2026\/\",\"name\":\"Festival 2026 - Dialogues des Carm\u00e9lites - Op\u00e9ra de Qu\u00e9bec\",\"isPartOf\":{\"@id\":\"https:\/\/operadequebec.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/operadequebec.com\/carmelites-festival-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/operadequebec.com\/carmelites-festival-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/Opera-de-quebec-jean-marie-zeitouni.jpg\",\"datePublished\":\"2026-05-11T16:33:02+00:00\",\"dateModified\":\"2026-07-12T22:34:26+00:00\",\"description\":\"Dialogues of the Carmelites, at the 2026 Qu\u00e9bec Opera Festival, presented at the Salle Louis-Fr\u00e9chette at the Grand Th\u00e9\u00e2tre de Qu\u00e9bec.\",\"breadcrumb\":{\"@id\":\"https:\/\/operadequebec.com\/carmelites-festival-2026\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/operadequebec.com\/carmelites-festival-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/operadequebec.com\/carmelites-festival-2026\/#primaryimage\",\"url\":\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/Opera-de-quebec-jean-marie-zeitouni.jpg\",\"contentUrl\":\"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/Opera-de-quebec-jean-marie-zeitouni.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/operadequebec.com\/carmelites-festival-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/operadequebec.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival 2026 &#8211; Dialogues des Carm\u00e9lites\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/operadequebec.com\/#website\",\"url\":\"https:\/\/operadequebec.com\/\",\"name\":\"Op\u00e9ra de Qu\u00e9bec\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/operadequebec.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival 2026 - Dialogues des Carm\u00e9lites - Op\u00e9ra de Qu\u00e9bec","description":"Dialogues of the Carmelites, at the 2026 Qu\u00e9bec Opera Festival, presented at the Salle Louis-Fr\u00e9chette at the Grand Th\u00e9\u00e2tre de Qu\u00e9bec.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/operadequebec.com\/carmelites-festival-2026\/","og_locale":"en_US","og_type":"article","og_title":"Festival 2026 - Dialogues des Carm\u00e9lites - Op\u00e9ra de Qu\u00e9bec","og_description":"Dialogues of the Carmelites, at the 2026 Qu\u00e9bec Opera Festival, presented at the Salle Louis-Fr\u00e9chette at the Grand Th\u00e9\u00e2tre de Qu\u00e9bec.","og_url":"https:\/\/operadequebec.com\/carmelites-festival-2026\/","og_site_name":"Op\u00e9ra de Qu\u00e9bec","article_modified_time":"2026-07-12T22:34:26+00:00","og_image":[{"width":1000,"height":1051,"url":"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/FDOQ-DDC-WEB-avec-titre-1000X1050-8Mai-2026.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/operadequebec.com\/carmelites-festival-2026\/","url":"https:\/\/operadequebec.com\/carmelites-festival-2026\/","name":"Festival 2026 - Dialogues des Carm\u00e9lites - Op\u00e9ra de Qu\u00e9bec","isPartOf":{"@id":"https:\/\/operadequebec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/operadequebec.com\/carmelites-festival-2026\/#primaryimage"},"image":{"@id":"https:\/\/operadequebec.com\/carmelites-festival-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/Opera-de-quebec-jean-marie-zeitouni.jpg","datePublished":"2026-05-11T16:33:02+00:00","dateModified":"2026-07-12T22:34:26+00:00","description":"Dialogues of the Carmelites, at the 2026 Qu\u00e9bec Opera Festival, presented at the Salle Louis-Fr\u00e9chette at the Grand Th\u00e9\u00e2tre de Qu\u00e9bec.","breadcrumb":{"@id":"https:\/\/operadequebec.com\/carmelites-festival-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/operadequebec.com\/carmelites-festival-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/operadequebec.com\/carmelites-festival-2026\/#primaryimage","url":"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/Opera-de-quebec-jean-marie-zeitouni.jpg","contentUrl":"https:\/\/operadequebec.com\/wp-content\/uploads\/2026\/05\/Opera-de-quebec-jean-marie-zeitouni.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/operadequebec.com\/carmelites-festival-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/operadequebec.com\/en\/"},{"@type":"ListItem","position":2,"name":"Festival 2026 &#8211; Dialogues des Carm\u00e9lites"}]},{"@type":"WebSite","@id":"https:\/\/operadequebec.com\/#website","url":"https:\/\/operadequebec.com\/","name":"Op\u00e9ra de Qu\u00e9bec","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/operadequebec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/operadequebec.com\/en\/wp-json\/wp\/v2\/pages\/17561"}],"collection":[{"href":"https:\/\/operadequebec.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/operadequebec.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/operadequebec.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/operadequebec.com\/en\/wp-json\/wp\/v2\/comments?post=17561"}],"version-history":[{"count":104,"href":"https:\/\/operadequebec.com\/en\/wp-json\/wp\/v2\/pages\/17561\/revisions"}],"predecessor-version":[{"id":21460,"href":"https:\/\/operadequebec.com\/en\/wp-json\/wp\/v2\/pages\/17561\/revisions\/21460"}],"wp:attachment":[{"href":"https:\/\/operadequebec.com\/en\/wp-json\/wp\/v2\/media?parent=17561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}